{"id":11442,"date":"2022-06-23T12:45:13","date_gmt":"2022-06-23T10:45:13","guid":{"rendered":"https:\/\/www.investmentworld.eu\/ch\/?p=11442"},"modified":"2022-06-23T12:46:51","modified_gmt":"2022-06-23T10:46:51","slug":"kames-capital-inflation-und-zinspolitik","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/kames-capital-inflation-und-zinspolitik\/","title":{"rendered":"BIT Capital : Inflation und Zinspolitik"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<p>\u00dcbertreibung nach unten: Inflations\u00e4ngste f\u00fchren zu irrationalem Marktverhalten. Die operative Performance der Unternehmen wird gegenw\u00e4rtig ausser Acht gelassen.<\/p>\n<\/div>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<hr \/>\n<p><span style=\"color: #00ffff;\">Sign up for our free newsletter to receive weekly news from BONDWorld <a style=\"color: #00ffff;\" href=\"index.php?option=com_acymailing&amp;view=user&amp;Itemid=107\"><strong>Click here to register for your free copy<\/strong><\/a><a style=\"color: #00ffff;\" href=\"index.php?option=com_acymailing&amp;view=user&amp;Itemid=1023\"><strong>\u00a0<\/strong><\/a><\/span><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong><strong><strong><strong><strong><strong><strong>Marcel Oldenkott, Gesch\u00e4ftsf\u00fchrer bei BIT Capital<br \/>\n<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/p>\n<hr \/>\n<ul>\n<li style=\"text-align: justify;\">Anhand bew\u00e4hrter Berechnungsmodelle oder Input-Faktoren des Marktes ist der Preisverfall vieler Technologieunternehmen nicht zu erkl\u00e4ren<\/li>\n<li style=\"text-align: justify;\">Notenbanken in schwieriger Lage: Weitere Leitzinserh\u00f6hungen werden nur bedingte Wirksamkeit bei der Inflationseinschr\u00e4nkung erzielen, k\u00f6nnen jedoch eine Rezession herbeif\u00fchren<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Die US-Inflationsrate kletterte im Mai auf 8,6 Prozent und damit auf den h\u00f6chsten Stand seit mehr als 40 Jahren. Steigende Preise bereiten immer mehr Menschen und Managern, vor allem aber den Zentralbanken grosses Kopfzerbrechen. Die FED f\u00fchrte j\u00fcngst die st\u00e4rkste Anhebung des Leitzinses seit 1994 um 75 Basispunkte auf die Spanne von nun 1,50 bis 1,75 Prozent durch. Es war bereits die dritte Anhebung in diesem Jahr. Auch die EZB avisiert f\u00fcr Juli mit einer Anhebung von 0,25 Prozentpunkten die erste Zinserh\u00f6hung in der Eurozone seit elf Jahren.<\/p>\n<p style=\"text-align: justify;\">Gleichzeitig hob die US-Notenbank die Inflationsprognose und senkte wiederum ihre Wachstumsprognose. Die B\u00f6rsen weltweit zeigten daraufhin deutliche Reaktionen: \u201eDer Markt wurde entlang aller Indizes, sowohl im Technologie-Sektor als auch im S&amp;P 500 in seiner gesamten Breite abverkauft\u201c, erkl\u00e4rt BIT Capital Gr\u00fcnder und Chief Investment Officer Jan Beckers.<\/p>\n<p style=\"text-align: justify;\"><strong>Marcel Oldenkott, Gesch\u00e4ftsf\u00fchrer bei BIT Capital, sieht die FED in einer schwierigen Lage:<\/strong> \u201cEine Erh\u00f6hung des Leitzinses entfaltet in der gegebenen Lage nicht unmittelbar Wirkung. Vor allem kann sie nicht die Teuerungsrate spezifischer G\u00fcter, wie \u00d6l, punktgenau adressieren.\u201d Auch wenn Leitzinserh\u00f6hungen f\u00fcr die \u00fcblichen Ursachen der Inflation ein probates Mittel seien, ist es unwahrscheinlich, dass sie aktuell die erw\u00fcnschte Wirkung entfalten.<\/p>\n<p style=\"text-align: justify;\">Denn die derzeitige Inflation sei vordergr\u00fcndig nicht nachfrageinduziert zu begr\u00fcnden, sondern vor allem auf exogene Schocks, wie den Ukraine-Krieg und die Lieferkettenunterbrechung in Asien zur\u00fcckzuf\u00fchren. \u201cWenn sich Input-Kosten f\u00fcr Unternehmen durch exogene Schocks erh\u00f6hen, ist ein Eingriff durch Zinsen nur bedingt wirksam\u201d, erkl\u00e4rt Marcel Oldenkott. Demnach k\u00f6nne beispielsweise kaum eine Auswirkung auf die hohen Energiepreise erwartet werden. Anders sieht es bei Verm\u00f6genswerten aus. Die Entwicklung von Aktien oder Immobilienwerten wird ged\u00e4mpft oder R\u00fcckg\u00e4ngig gemacht. Tech-Werte und andere \u201cLong-Duration-Assets\u201d wie Immobilien leiden in diesem Umfeld \u00fcberproportional. \u201cViele der Gewinne von Technologieunternehmen entstehen erst in der Zukunft und m\u00fcssen nun folgend mit einem h\u00f6heren Faktor abgezinst werden. Zuletzt reagierte der Markt mit einem deutlichen Abverkauf solcher Titel, ungeachtet dessen, dass Technologieunternehmen erh\u00f6hte Kosten h\u00e4ufig auch an Kunden weitergegeben k\u00f6nnen\u201d, erkl\u00e4rt Fondsmanager Jan Beckers. Anhand von bew\u00e4hrten Berechnungsmodellen oder den Input-Faktoren des Marktes sei der Preisverfall vieler Tech-Unternehmen nicht rational zu erkl\u00e4ren. \u201cWir kommen aus einer Phase in der Asset-Preise au\u00dferordentlich hoch waren, insofern macht eine Korrektur durchaus Sinn. Doch was wir hier sehen ist schlicht irrational und auf Unsicherheit und Angst zur\u00fcckzuf\u00fchren\u201d, <strong>so Jan Beckers.<\/strong><\/p>\n<p style=\"text-align: justify;\">Als digitaler Asset Manager behalte BIT Capital seinen mittel- bis langfristigen Fokus. Werte der Old Economy, die zwar kurzfristig attraktiv erscheinen, jedoch nicht zum Mandat eines zukunftsorientierten Technologiefonds geh\u00f6ren und kein dynamisches Wachstum h\u00e4tten, k\u00e4men dabei nicht in Frage. Auch eine gr\u00f6ssere Cashposition f\u00fchre schlicht zu einer negativen Realrendite. \u201cBei BIT Capital legen wir in dieser Phase einen verst\u00e4rkten Fokus auf die operative Performance und Profitabilit\u00e4t der Unternehmen. Wir konzentrieren uns also auf eine enge Auswahl, die sich auf einem erkennbaren Path to Profitability befindet. So werden 9 unserer 10 gr\u00f6ssten Positionen im Portfolio im zweiten Quartal 2022 profitabel sein und das bei einem durchschnittlichen j\u00e4hrlichen Umsatzwachstum von \u00fcber 40 %. Dennoch verlieren auch solche Unternehmen aktuell einen Grossteil ihrer Marktkapitalisierung.\u201d, <strong>so Marcel Oldenkott.<\/strong><\/p>\n<p style=\"text-align: justify;\">Die Folge sind zum Teil seit Jahren ungesehen niedrige Multiples. So sei das Kurs-Gewinn-Verh\u00e4ltnis einiger Unternehmen im Portfolio unter drei gefallen. \u201cWir finden viele attraktive Technologieunternehmen mit aussergew\u00f6hnlich lukrativen Bewertungen\u201d, sagt Marcel Oldenkott. Auch der Nasdaq Internet Index handelt derzeit unterhalb seines pre-COVID-Levels und nahe den Werten von 2017. Der Markt preist damit den Fortschritt durch Digitalisierung der letzten f\u00fcnf Jahre vollst\u00e4ndig aus.<\/p>\n<p style=\"text-align: justify;\"><strong>Der Experte erg\u00e4nzt:<\/strong> \u201cGegenw\u00e4rtig ist die Unterscheidung in der operativen Performance innerhalb dieses irrationalen Abverkaufs noch nicht sichtbar und es ist nicht abzusehen, wann genau die M\u00e4rkte wieder anhand von fundamentalen Kriterien bepreisen. Aber man wird diese Unterscheidung in den Returns der Unternehmen \u00fcber einen l\u00e4ngeren Horizont deutlich erkennen.\u201d Wom\u00f6glich werde dies der Fall sein, wenn \u00fcber Monate eine stabile oder leicht sinkende Inflation zu erkennen ist und vor allem der Markt daran glaubt, dass die Zentralbanken die Situation unter Kontrolle bekommen. So resultiere die Angst am Markt nicht vorrangig aus steigenden Zinsen, sondern bestehe vielmehr vor dem Schreckgespenst einer au\u00dfer Kontrolle geratenen Inflation.<\/p>\n<p>Source: BondWorld.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00dcbertreibung nach unten: Inflations\u00e4ngste f\u00fchren zu irrationalem Marktverhalten. Die operative Performance der Unternehmen wird gegenw\u00e4rtig ausser Acht gelassen.<\/p>\n","protected":false},"author":4,"featured_media":11443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[228],"class_list":["post-11442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marktanalyse","tag-bit-capital"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/11442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=11442"}],"version-history":[{"count":3,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/11442\/revisions"}],"predecessor-version":[{"id":11446,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/11442\/revisions\/11446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media\/11443"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=11442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=11442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=11442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}