{"id":13619,"date":"2022-06-20T10:18:46","date_gmt":"2022-06-20T08:18:46","guid":{"rendered":"https:\/\/www.advisorworld.ch\/?p=13619"},"modified":"2022-06-20T10:18:46","modified_gmt":"2022-06-20T08:18:46","slug":"generalversammlung-von-raiffeisen-schweiz-genehmigt-jahresrechnung-und-bestaetigt-verwaltungsrat-im-amt","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/generalversammlung-von-raiffeisen-schweiz-genehmigt-jahresrechnung-und-bestaetigt-verwaltungsrat-im-amt\/","title":{"rendered":"Generalversammlung von Raiffeisen Schweiz genehmigt Jahresrechnung und best\u00e4tigt Verwaltungsrat im Amt"},"content":{"rendered":"<p style=\"text-align: justify;\">Die Generalversammlung von Raiffeisen Schweiz hat s\u00e4mtliche Antr\u00e4ge des Verwaltungsrats genehmigt.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/starthostunlimiteddmffassi-ss.stackstaging.com\/advisorworld.ch\/newsletter\">Abonnieren Sie unseren kostenloser Newsletter<\/a><\/strong><\/p>\n<hr \/>\n<p><strong>Thomas A. M\u00fcller, Verwaltungsratspr\u00e4sident von Raiffeisen Schweiz<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Sowohl Verwaltungsratspr\u00e4sident Thomas A. M\u00fcller als auch die weiteren Verwaltungsr\u00e4tinnen und Verwaltungsr\u00e4te wurden in ihren \u00c4mtern best\u00e4tigt.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Die Vertreterinnen und Vertreter der Raiffeisenbanken genehmigten die Jahresrechnung 2021 von Raiffeisen Schweiz und die konsolidierte Jahresrechnung 2021 der Raiffeisen Gruppe.<\/strong><\/p>\n<p style=\"text-align: justify;\">Die Raiffeisenbanken haben an der ordentlichen Generalversammlung in Locarno s\u00e4mtliche Antr\u00e4ge des Verwaltungsrats gutgeheissen. Die Vertreterinnen und Vertreter der Raiffeisenbanken haben alle Mitglieder des Verwaltungsrates f\u00fcr weitere zwei Jahre wiedergew\u00e4hlt. Verwaltungsratspr\u00e4sident Thomas A. M\u00fcller wurde mit einer Mehrheit von 96 Prozent in seinem Amt best\u00e4tigt.<\/p>\n<p style=\"text-align: justify;\">Im Jahr 2021 erwirtschaftete die Raiffeisen Gruppe mit einem Gewinn von 1,07 Milliarden Franken das beste Ergebnis ihrer Geschichte. Die Vertreterinnen und Vertreter der Raiffeisenbanken genehmigten die Jahresrechnung 2021 von Raiffeisen Schweiz und die konsolidierte Jahresrechnung 2021 der Raiffeisen Gruppe.<\/p>\n<p style=\"text-align: justify;\">Der Generalversammlung wurde auch der Verg\u00fctungsbericht 2021 zur Konsultativabstimmung vorgelegt. Zudem stimmten die Vertreterinnen und Vertreter der Raiffeisenbanken konsultativ \u00fcber den Verg\u00fctungsrahmen des Verwaltungsrates und der Gesch\u00e4ftsleitung von Raiffeisen Schweiz f\u00fcr das Gesch\u00e4ftsjahr 2023 ab. Eine deutliche Mehrheit der Stimmberechtigten hat den Verg\u00fctungsbericht 2021 wie auch den Verg\u00fctungsrahmen f\u00fcr den Verwaltungsrat und die Gesch\u00e4ftsleitung von Raiffeisen Schweiz f\u00fcr das Gesch\u00e4ftsjahr 2023 gutgeheissen.<\/p>\n<p style=\"text-align: justify;\"><strong>Thomas A. M\u00fcller, Verwaltungsratspr\u00e4sident von Raiffeisen Schweiz:<\/strong> \u00abIch freue mich \u00fcber die positiven Abstimmungsresultate. Zusammen mit dem Verwaltungsratsmitgliedern werde ich mich weiter daf\u00fcr einsetzen, die Nummer Eins bei Kundinnen und Kunden zu sein und den Dialog in der Gruppe zu st\u00e4rken. Mit unserer Strategie 2025 sind wir auf dem richtigen Weg. Das zeigt auch das gute Jahresergebnis 2021.\u00bb<\/p>\n<p style=\"text-align: justify;\">Quelle: AdvisorWorld.ch<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Die Generalversammlung von Raiffeisen Schweiz hat s\u00e4mtliche Antr\u00e4ge des Verwaltungsrats genehmigt.<\/p>\n","protected":false},"author":4,"featured_media":11256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[49],"tags":[84],"class_list":["post-13619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-raiffeisen"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/13619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=13619"}],"version-history":[{"count":0,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/13619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=13619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=13619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=13619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}