{"id":13724,"date":"2022-06-27T08:57:26","date_gmt":"2022-06-27T06:57:26","guid":{"rendered":"https:\/\/www.advisorworld.ch\/?p=13724"},"modified":"2022-06-27T08:57:26","modified_gmt":"2022-06-27T06:57:26","slug":"redwheel-zum-neuen-rohstoff-superzyklus-gruene-welle-fuer-die-emerging-markets","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/redwheel-zum-neuen-rohstoff-superzyklus-gruene-welle-fuer-die-emerging-markets\/","title":{"rendered":"Redwheel zum neuen Rohstoff-Superzyklus: Gr\u00fcne Welle f\u00fcr die Emerging Markets"},"content":{"rendered":"<p style=\"text-align: justify;\">Redwheel : Um bis 2050 CO2-neutral zu werden, m\u00fcssen etwa 56 Billionen US-Dollar in Infrastruktur investiert werden. Metalle wie Kupfer, Lithium und Kobalt spielen hier eine zentrale Rolle. Der Klimaschutz befeuert somit die Nachfrage und st\u00e4rkt die Wirtschaft der exportierenden Schwellenl\u00e4nder.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/advisorworld.ch\/newsletter\">Abonnieren Sie unseren kostenloser Newsletter<\/a><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: center;\"><strong>Von James Johnstone, Co-Head Emerging and Frontier Markets, Redwheel<br \/>\n<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Die weltweiten Bem\u00fchungen, die Klimakrise zu bew\u00e4ltigen, werden ein massives Elektrifizierungs- und Dekarbonisierungsprogramm erfordern. Sie d\u00fcrften in den kommenden Jahrzehnten eine ganz erhebliche Rohstoffnachfrage hervorrufen. Es ist daher wahrscheinlich, dass damit die Voraussetzungen f\u00fcr den Beginn des n\u00e4chsten \u00abRohstoff-Superzyklus\u00bb gegeben sind. Wer sind die Gewinner und Verlierer dieser Entwicklung?<\/p>\n<p style=\"text-align: justify;\">Um einen Superzyklus auszul\u00f6sen, der die Preise bestimmter Rohstoffe \u00fcber viele Jahre, teilweise f\u00fcr mehr als ein Jahrzehnt steigen l\u00e4sst, ist das Zusammentreffen mehrerer Faktoren n\u00f6tig. Die Ereignisse folgen in der Regel auf eine l\u00e4ngere Periode schleppender Nachfrage und mehrere Jahre mit geringen Investitionsausgaben in der Bergbauindustrie. Und da der Betrieb von Minen eine notorisch zyklische Branche und sehr kapitalintensiv ist, dauert es, bis neue Kapazit\u00e4ten aufgebaut sind. Das heisst, dass die Preise bei einem unerwarteten Anstieg der Nachfrage \u00fcber mehrere Jahre hinweg hoch bleiben k\u00f6nnen, bevor zus\u00e4tzliches Angebot in die Produktion gelangt. Im Umkehrschluss k\u00f6nnen Minenbetreiber bei einem Nachfrager\u00fcckgang gezwungen sein, Investitionsvorhaben bis weit in den n\u00e4chsten Zyklus hinein aufzuschieben.<\/p>\n<p style=\"text-align: justify;\">Der letzte Superzyklus etwa wurde zu Beginn des Jahrtausends durch den Infrastrukturboom in China ausgel\u00f6st: Nach fast zwanzig Jahren stagnierender Rohstoffpreise und geringen Investitionen stieg die Nachfrage nach \u00d6l, Kupfer, Eisenerz und Stahl enorm. Der resultierende Preisruck bei diesen Rohstoffen war f\u00fcr die Exporteure von Vorteil, barg aber auch grosse Herausforderungen f\u00fcr Verbraucher in anderen Teilen der Welt.<\/p>\n<p style=\"text-align: justify;\">W\u00e4hrend zwischen der Geschichte und den M\u00e4rkten heute einige Parallelen zu erkennen sind, ist jedoch zu ber\u00fccksichtigen, dass jeder Zyklus seine ganz eigenen Merkmale und Triebkr\u00e4fte hat. Es ist zu erwarten, dass der aktuelle Zyklus von der sogenannten gr\u00fcnen Welle angetrieben wird.<\/p>\n<p style=\"text-align: justify;\"><strong>Die gr\u00fcne Welle<\/strong><\/p>\n<p style=\"text-align: justify;\">Wie etwa die Klimakonferenz COP-26 in Glasgow und anderen wichtige globalen Initiativen in den letzten Jahren gezeigt haben, wird der Wunsch, etwas gegen die Klimakrise zu unternehmen, weltweit von einer ausserordentlichen Dynamik getragen. Die Gesellschaft muss die Abh\u00e4ngigkeit von fossilen Brennstoffen rasch verringern und sich von einer \u00fcberm\u00e4ssig konzentrierten Energieversorgung l\u00f6sen, bevor es zu sp\u00e4t ist. Dies bedeutet, dass mehr Energie aus erneuerbaren Quellen wie Windkraft, Solarenergie und Wasserstoff erzeugt werden muss und Elektrofahrzeuge Verbrennungsmotoren schrittweise ersetzen sollten.<\/p>\n<p style=\"text-align: justify;\">Um bis zum Jahr 2050 CO2-neutral zu werden, m\u00fcssen sch\u00e4tzungsweise etwa 56 Billionen US-Dollar in entsprechende Infrastrukturprojekte investiert werden. Gerade Metalle wie Kupfer, Lithium und Kobalt sind f\u00fcr die Dekarbonisierung von entscheidender Bedeutung. Bemerkenswert ist, dass die meisten Rohstoffe, die den n\u00e4chsten Superzyklus antreiben, in den Schwellenl\u00e4ndern der n\u00e4chsten Generation gef\u00f6rdert werden.<\/p>\n<p style=\"text-align: justify;\"><strong>Kupfer und Lithium<\/strong><\/p>\n<p style=\"text-align: justify;\">Kupfer ist zu dem gr\u00fcnen Metall geworden, auf das Anleger ihren Fokus legen sollten: In einer Drei-Megawatt-Windturbine werden fast f\u00fcnf Tonnen Kupfer verbaut und auch in Stromnetzen ist Kupfer ein unerl\u00e4sslicher Werkstoff. Mehr als ein Drittel der weltweiten Kupferreserven lagern in zwei s\u00fcdamerikanischen Schwellenl\u00e4ndern der n\u00e4chsten Generation, in Chile und Peru. In Afrika werden die Demokratische Republik Kongo und Sambia zu immer wichtigeren Kupferlieferanten. First Quantum Minerals etwa betreibt in Sambia eine der gr\u00f6ssten Kupferminen der Welt. Das Unternehmen ist gut positioniert, um von einer Aufwertung des Kupferpreises in den n\u00e4chsten zehn Jahren zu profitieren: Die Nachfrage w\u00e4chst stetig, und das Angebot ist beschr\u00e4nkt.<\/p>\n<p style=\"text-align: justify;\">Die zunehmende Verbreitung von Elektrofahrzeugen ist ein klarer Nachfragetreiber auch f\u00fcr verschiedene andere Metalle, wie etwa Lithium. Die Lithiumnachfrage d\u00fcrfte in den n\u00e4chsten Jahren um 20 bis 25 Prozent pro Jahr steigen und es ist davon auszugehen, dass die Lithiumpreise von dieser starken Nachfrage \u2013 in Verbindung mit der typischen Verz\u00f6gerung von f\u00fcnf bis sieben Jahren bei der Inbetriebnahme neuer Minen \u2013 profitieren werden. Zwei der gr\u00f6ssten Lithiumproduzenten der Welt sind Chile und Argentinien. SQM etwa betreibt in Chile eine der gr\u00f6ssten Lithiumminen der Welt und ist gut positioniert, um von diesem Preisumfeld zu profitieren. Das Unternehmen d\u00fcrfte im kommenden Jahr ein robustes Produktionswachstum verzeichnen und seine Projekte sind kosteng\u00fcnstiger als die vieler seiner Konkurrenten.<\/p>\n<p style=\"text-align: justify;\"><strong>Abb. 1: Aussichten f\u00fcr Lithium: Die Nachfrage enteilt dem Angebot<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13725 aligncenter\" src=\"https:\/\/www.investmentworld.eu\/ch\/wp-content\/uploads\/2024\/01\/d500e2ffdc3ed53557126e1a651ed404.png\" alt=\"27062022\" width=\"600\" height=\"361\" \/><\/p>\n<p style=\"text-align: center;\"><strong>Quelle: Redwheel und Bloomberg, Stand vom 31.12.2021.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Gewinner und Verlierer<\/strong><\/p>\n<p style=\"text-align: justify;\">In jedem Rohstoff-Superzyklus gibt es Gewinner und Verlierer. Einzelne Unternehmen \u2013 wie First Quantum und SQM \u2013 k\u00f6nnen von der gr\u00fcnen Welle profitieren, die bereits Fahrt aufnimmt. Netto-Rohstoffexportl\u00e4nder k\u00f6nnen \u00fcberdies von einer verbesserten Haushaltslage, h\u00f6heren Staatsausgaben, einer Zunahme von internen Infrastrukturinvestitionen und neuen Arbeitspl\u00e4tzen profitieren. Gleichzeitig setzt eine steigende Inflation die Verbraucher in anderen Teilen der Welt, welche wichtige Rohstoffe importieren, unter Druck. Die entsprechenden Auswirkungen sind bereits sp\u00fcrbar. Der Einmarsch Russlands in der Ukraine hat bereits bestehende Angebotsdefizite noch verst\u00e4rkt.<\/p>\n<p style=\"text-align: justify;\">Daher sind L\u00e4nder zu meiden, die einer herausfordernden, mit h\u00f6heren Rohstoffpreisen und steigender Inflation einhergehenden Konsumdynamik ausgesetzt sind. Es lohnt sich hier, sich vorerst auf die Nettoexporteure dieser Rohstoffe zu konzentrieren, bei denen das Ungleichgewicht zwischen Angebot und Nachfrage auf ein positives k\u00fcnftiges Marktumfeld schliessen l\u00e4sst.<\/p>\n<p style=\"text-align: justify;\">Durch den st\u00e4ndigem Kontakt mit den Bergbauunternehmen ist zu erfahren, dass diese die Bedeutung eines verantwortungsvollen Bergbaus bekr\u00e4ftigen \u2013 in Bezug auf die Sicherheit der Arbeiter, die Umwelt, in der sie arbeiten und die Unternehmensf\u00fchrung. Erfolgreiches ESG-Management Faktoren erm\u00f6glicht es den Unternehmen, potenziell kostspielige beziehungsweise nachteilige Ereignisse zu vermeiden, die auch ihre finanzielle Stabilit\u00e4t beeintr\u00e4chtigen w\u00fcrden.<\/p>\n<p style=\"text-align: justify;\"><strong>Ein Blick in die Zukunft<\/strong><\/p>\n<p style=\"text-align: justify;\">Obwohl der n\u00e4chste Rohstoff-Superzyklus viele Merkmale der vorangegangenen Zyklen aufweisen d\u00fcrfte, ist zu erwarten, dass diesmal eine Reihe besonderer Rohstoffe im Zentrum steht: Kupfer, Lithium, Kobalt und andere Metalle, die f\u00fcr die Dekarbonisierung unerl\u00e4sslich sind, werden am st\u00e4rksten profitieren \u2013 und diese Rohstoffe werden haupts\u00e4chlich in den Schwellenl\u00e4ndern der n\u00e4chsten Generation in S\u00fcdamerika, Afrika und Asien gef\u00f6rdert. Daher sind Rohstoffe auch eines von drei Hauptthemen im Zentrum des Redwheel Next Generation Emerging Markets Fonds. Eine Strategie, die sich auszahlt: Trotz erh\u00f6hter Marktvolatilit\u00e4t erzielte der Fond in den drei Jahren seit seiner Auflegung eine Top-Quartil-Performance und eine Rendite von 77 Prozent \u2013 der Index dagegen nur sechs Prozent.<\/p>\n<p style=\"text-align: justify;\">Quelle: AdvisorWorld.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Redwheel : Um bis 2050 CO2-neutral zu werden, m\u00fcssen etwa 56 Billionen US-Dollar in Infrastruktur investiert werden. Metalle wie Kupfer, Lithium und Kobalt spielen hier eine zentrale Rolle. Der Klimaschutz befeuert somit die Nachfrage und st\u00e4rkt die Wirtschaft der exportierenden Schwellenl\u00e4nder.<\/p>\n","protected":false},"author":4,"featured_media":13126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[332],"class_list":["post-13724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marktanalyse","tag-redwheel"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/13724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=13724"}],"version-history":[{"count":0,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/13724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=13724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=13724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=13724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}