{"id":19997,"date":"2023-12-06T15:56:40","date_gmt":"2023-12-06T14:56:40","guid":{"rendered":"https:\/\/www.advisorworld.ch\/?p=19997"},"modified":"2024-01-22T16:17:47","modified_gmt":"2024-01-22T15:17:47","slug":"bit-capital-anlagechancen-entlang-der-ki-infrastruktur-die-neue-aera-der-rechenzentren","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/bit-capital-anlagechancen-entlang-der-ki-infrastruktur-die-neue-aera-der-rechenzentren\/","title":{"rendered":"BIT Capital: Anlagechancen entlang der KI-Infrastruktur -Die neue \u00c4ra der Rechenzentren"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><strong>BIT Capital<\/strong> : KI-bezogene Investitionsausgaben f\u00fcr Rechenzentren k\u00f6nnten sich bis 2026 verdoppeln und weltweit ein Volumen von 556 Mrd. US-Dollar erreichen.<\/h5>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"\/newsletter\">Abonnieren Sie unseren kostenloser Newsletter<\/a><\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Jan Beckers, Gr\u00fcnder und CIO von BIT Capital<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Der Grund:<\/strong> Eine stetige Weiterentwicklung und Skalierung von KI-Modellen erh\u00f6ht die Anforderungen an technologische Infrastruktur und l\u00e4sst auch die Nachfrage nach leistungsstarker Hardware in die H\u00f6he schnellen. Denn wesentliche Voraussetzung f\u00fcr die Anwendung der Technologie ist die Verf\u00fcgbarkeit leistungsstarker KI-Server.<\/p>\n<p style=\"text-align: justify;\">Um Kapazit\u00e4ten f\u00fcr solche Hochleistungsserver zu schaffen, m\u00fcssen nicht nur alte Rechenzentren umger\u00fcstet, sondern auch neue errichtet werden. Zugang zu kosteng\u00fcnstigem Strom sowie Expertise im operativen Betrieb bestimmen, wer sich als f\u00fchrender Anbieter in diesem Segment etablieren kann.<\/p>\n<p style=\"text-align: justify;\"><strong>Applied Digital ist ein Betreiber von Datenzentren, der mit seiner Energieeffizienz, vergleichsweise geringen Stromkosten sowie Expertise bestens positioniert ist, um vom steigenden Bedarf nach KI-Rechenleistung zu profitieren.<\/strong> Das Unternehmen vermietet \u00fcber einen Cloud-Zugang die Rechenpower von Nvidia Graphical Processing Units (GPUs) auf Stunden- oder Monatsbasis und generiert so eine beeindruckende Bruttomarge von \u00fcber 80 Prozent. Applied Digital baut seine Kapazit\u00e4ten weiter aus und errichtet ein Datencenter mit einem Leistungsverm\u00f6gen von 200 Megawatt f\u00fcr Accelerated Computing, um so bis zu 110.000 Nvidia H100 GPUs zu betreiben. Zum Vergleich: Mit 21.000 GPUs der \u00e4lteren A100-Generation verf\u00fcgte Meta Ende 2022 \u00fcber eines der weltweit gr\u00f6\u00dften GPU-Rechencluster.<\/p>\n<p style=\"text-align: justify;\">Als eines von nur f\u00fcnf KI-Cloud-Unternehmen in den USA mit dem begehrten Nvidia Elite-Partner Status geniesst Applied Digital vorrangigen Zugang zu den stark nachgefragten GPUs. Wir schauen daher gespannt auf die n\u00e4chsten Quartale und das Wachstum von Applied Digital im KI-Cloud-Segment.<\/p>\n<p style=\"text-align: justify;\">Quelle : InvestmentWorld<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BIT Capital : KI-bezogene Investitionsausgaben f\u00fcr Rechenzentren k\u00f6nnten sich bis 2026 verdoppeln und weltweit ein Volumen von 556 Mrd. US-Dollar erreichen.<\/p>\n","protected":false},"author":4,"featured_media":23142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":null,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[228,749],"class_list":["post-19997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marktanalyse","tag-bit-capital","tag-ki"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/19997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=19997"}],"version-history":[{"count":2,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/19997\/revisions"}],"predecessor-version":[{"id":23141,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/19997\/revisions\/23141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media\/23142"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=19997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=19997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=19997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}