{"id":2035,"date":"2016-05-27T06:00:00","date_gmt":"2016-05-27T06:00:00","guid":{"rendered":"http:\/\/starthostunlimiteddmffassi-ss.stackstaging.com\/bondworld.ch\/home\/sites\/20b\/7\/760c69a11c\/public_html\/investmentworld.ch\/index.php\/2016\/05\/27\/orientierungslos\/"},"modified":"2016-05-27T06:00:00","modified_gmt":"2016-05-27T06:00:00","slug":"orientierungslos","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/orientierungslos\/","title":{"rendered":"Orientierungslos?"},"content":{"rendered":"<p style=\"text-align: justify;\">Die abgelaufene Woche an den internationalen Kapitalm&auml;rkten begann uneinheitlich: W&auml;hrend milliardenschwere &Uuml;bernahmeaktivit&auml;ten die Nachrichtenlage auf Unternehmensebene bestimmten, lag makro&ouml;konomisch vor allem Japan im Fokus der Anleger. Der vorl&auml;ufige japanische Einkaufsmanagerindex f&uuml;r das verarbeitende Gewerbe fiel mit 47.6 Punkten auf das niedrigste Niveau seit Dez. 2012&#8230;&#8230;<\/p>\n<p>  <!--more--> <\/p>\n<hr \/>\n<p><span style=\"color: #00ccff;\">Sign up for our free newsletter to receive weekly news from BONDWorld <a href=\"index.php?option=com_acymailing&amp;view=user&amp;Itemid=107\"><span style=\"color: #00ccff;\"><strong>Click here to register for your free copy<\/strong><\/span><\/a><a href=\"index.php?option=com_acymailing&amp;view=user&amp;Itemid=1023\"><span style=\"color: #00ccff;\"><strong>&nbsp;<\/strong><\/span><\/a><\/span><\/p>\n<hr \/>\n<p><strong>Stefan Scheurer Vice President, Global Capital Markets &amp; Thematic Research<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Passend f&uuml;r die schw&auml;chelnde japanische Konjunktur, fand das G7Finanzministertreffen in Sendai, Japan, statt. Neben einem klaren Bekenntnis gegen einen Austritt Gro&szlig;britanniens aus der Europ&auml;ischen Union, hie&szlig; es in der Abschlusserkl&auml;rung, die Finanzminister h&auml;tten &#8220;existierende G7-Vereinbarungen zu Wechselkursen best&auml;tigt&#8221; sowie &#8220;die Wichtigkeit hervorgehoben, dass alle L&auml;nder von wetteifernder Abwertung absehen&#8221;. Doch dies sollte vor dem Hintergrund gesehen werden, da die japanische Regierung zuletzt angedeutet hatte, ebensolche Ma&szlig;nahmen gegen den derzeit starken Yen ergreifen zu wollen. Beispiel: die japanischen Exporte f&uuml;r April wurden aufgrund eines st&auml;rkeren Yens st&auml;rker belastet als erwartet &ndash; sie sanken um 10,1% j\/j. Japans Finanzminister Aso lie&szlig; daraufhin nicht lange auf sich warten. Er bezeichnete die Wechselkursschwankungen zwischen dem W&auml;hrungspaar Yen\/USD in den letzten Wochen als &bdquo;nicht normal&ldquo;, sprich zu &bdquo;einseitig&ldquo; und &bdquo;spekulativ&ldquo;. Jene Rhetorik d&uuml;rfte anhalten, wenn sich die Staats- und Regierungschefs der G7L&auml;nder gegen Ende der Woche zum Gipfel im japanischen Ise-Shima treffen.&nbsp;&nbsp;<\/p>\n<p style=\"text-align: justify;\">Doch f&uuml;r Japan bzw. f&uuml;r einen schw&auml;cheren Yen k&ouml;nnte die anhaltende konjunkturelle Erholung der US-Wirtschaft sprechen, die die T&uuml;r f&uuml;r eine weitere Zinserh&ouml;hung in den kommenden Monaten weiter aufgesto&szlig;en hat. Und: Wenn der Abwertungswettlauf der Zentralbanken tats&auml;chlich gestoppt w&uuml;rde, w&uuml;rde dies der USNotenbank (Fed) zus&auml;tzlichen Handlungsspielraum verschaffen.<\/p>\n<p style=\"text-align: justify;\">\uf0b7 Lag die Wahrscheinlichkeit vor fast zwei Wochen noch bei nahe 0%, stieg sie zuletzt f&uuml;r eine Zinserh&ouml;hung im Juni 2016 auf fast 40%.<\/p>\n<p style=\"text-align: justify;\">\uf0b7 Das d&uuml;rfte nicht nur die Anleihem&auml;rkte zu einem weiteren Einpreisen h&ouml;herer Zinsprognosen bewegen, sondern auch den US-Dollar st&auml;rker werden lassen. So stieg der Dollar-Index zuletzt auf ein neues 7-Wochen-Hoch. \uf0b7 Im Umkehrschluss k&ouml;nnte dies f&uuml;r einen schw&auml;cheren Yen sorgen, wenngleich wechselkursseitig sich auch Auswirkungen beim chinesischen Renminbi (RMB) bemerkbar machen d&uuml;rften &ndash; jener fiel auf ein neues 11-Wochen-Tief gegen&uuml;ber dem USDollar.<\/p>\n<p style=\"text-align: justify;\">\uf0b7 Und: Unsere Grafik der Woche deutet auf eine weitere Schw&auml;che des RMB hin.<\/p>\n<p style=\"text-align: justify;\">Mit Blick auf die kommende Woche werden eine Vielzahl an Stimmungs- und real&ouml;konomischen Indikatoren ver&ouml;ffentlicht. In den USA deutet neben der Entwicklung der H&auml;userpreise (Di) auch der Einkaufsmanagerindex f&uuml;r das verarbeitende Gewerbe der Region Chicago (Di) und das Verbrauchervertrauen (Di) auf eine sich verbessernde Dynamik des US-Wirtschaftswachstum hin. Zusammen mit einem ISM-Einkaufsmanagerindex (Mi), der sich weiter in der expansiven Zone halten d&uuml;rfte, und einem robusten Arbeitsmarkt (Mi-Fr), k&ouml;nnte die Wahrscheinlichkeit einer bevorstehenden Zinserh&ouml;hung weiter anstiegen lassen.&nbsp;&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Im Euroraum<\/strong> werden neben diversen Stimmungsindikatoren (Mo) auch die Kerninflation (Di) und die Einzelhandelsums&auml;tze (Fr) ver&ouml;ffentlicht. Fokus d&uuml;rfte allerdings auf der Europ&auml;ischen Zentralbank (EZB) liegen (Do), wenngleich angesichts des erst im M&auml;rz beschlossenen umfassenden Ma&szlig;nahmenb&uuml;ndels sich die EZB nun auf dessen Umsetzung und Bewertung konzentriert. Daher d&uuml;rfte geldpolitisch eher ein Sommer des Abwartens bevorstehen. L&auml;nderspezifisch werden in Deutschland die Verbraucherpreisdaten und die Einzelhandelsums&auml;tze (Mo) bekanntgegeben bzw. die Arbeitsmarktdaten f&uuml;r Mai (Di). Im Vereinigten K&ouml;nigreich steht der Einkaufsmanagerindex f&uuml;r das verarbeitende Gewerbe am Mittwoch im Fokus.<\/p>\n<p style=\"text-align: justify;\"><strong>In Japan<\/strong> geht zur Mitte der kommenden Woche die aktuelle Sitzungsperiode zu Ende. Dies k&ouml;nnte die Regierung um Premierminister Abe zum Anlass nehmen, ihre Entscheidung bez&uuml;glich der f&uuml;r April 2017 avisierten Mehrwertsteuererh&ouml;hung bekanntzugeben. Entscheidend daf&uuml;r k&ouml;nnte die Entwicklung des inl&auml;ndischen Konsums (Mo) sein, aber auch das Verbrauchervertrauen (Do). Die erw&auml;hnte Yen-St&auml;rke k&ouml;nnte sich zumindest teils in der Industrieproduktion (Di) niederschlagen.<\/p>\n<p style=\"text-align: justify;\">Die prognostizierte Schw&auml;che des RMB k&ouml;nnte durch die Ver&ouml;ffentlichung der Einkaufsmanagerindizes f&uuml;r das verarbeitende Gewerbe (Mi) in China weitere Nahrung erhalten. Der offizielle wie auch privatwirtschaftliche Index deuten auf ein nachlassendes Konjunkturmomentum im Reich der Mitte hin, was unser China GDP Tracker bereits seit l&auml;ngerem induziert.<\/p>\n<p style=\"text-align: justify;\">Gem&auml;&szlig; den Positionierungen am Optionsmarkt bzw. den RelativeSt&auml;rke-Indizes (RSI) befinden sich die internationalen Aktienm&auml;rkte aktuell in einem &bdquo;neutralen&ldquo; Niveau, wenngleich der Anteil der B&auml;ren vor dem Hintergrund zunehmender (geo-)politischer Risiken leicht gestiegen ist. W&auml;hrend geringe Handelsvolumina auf hohe Kassenbest&auml;nde hindeuten, geht die Orientierungssuche weiter und damit verbunden eine zu erwartend h&ouml;here Volatilit&auml;t<\/p>\n<p>Quelle: BondWorld.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die abgelaufene Woche an den internationalen Kapitalm&auml;rkten begann uneinheitlich: W&auml;hrend milliardenschwere &Uuml;bernahmeaktivit&auml;ten die Nachrichtenlage auf Unternehmensebene bestimmten, lag makro&ouml;konomisch vor allem Japan im Fokus der Anleger. Der vorl&auml;ufige japanische Einkaufsmanagerindex f&uuml;r das verarbeitende Gewerbe fiel mit 47.6 Punkten auf das niedrigste Niveau seit Dez. 2012&#8230;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[53],"tags":[80],"class_list":["post-2035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allianz-g-i-die-woche-voraus","tag-allianz-gi"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=2035"}],"version-history":[{"count":0,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/2035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media\/3646"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=2035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=2035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}