{"id":3137,"date":"2017-11-06T07:00:00","date_gmt":"2017-11-06T07:00:00","guid":{"rendered":"http:\/\/starthostunlimiteddmffassi-ss.stackstaging.com\/bondworld.ch\/home\/sites\/20b\/7\/760c69a11c\/public_html\/investmentworld.ch\/index.php\/2017\/11\/06\/st-galler-kantonalbank-die-weltwirtschaft-waechst-die-aktionaere-freuen-sich\/"},"modified":"2020-02-04T09:00:03","modified_gmt":"2020-02-04T08:00:03","slug":"st-galler-kantonalbank-die-weltwirtschaft-waechst-die-aktionaere-freuen-sich","status":"publish","type":"post","link":"https:\/\/www.investmentworld.eu\/ch\/st-galler-kantonalbank-die-weltwirtschaft-waechst-die-aktionaere-freuen-sich\/","title":{"rendered":"St.Galler Kantonalbank: Die Weltwirtschaft w\u00e4chst, die Aktion\u00e4re freuen sich"},"content":{"rendered":"<p style=\"text-align: justify;\">Der Internationale W\u00e4hrungsfonds IWF hat seine Prognose f\u00fcr das Wachstum der Weltwirtschaft f\u00fcr 2017 von 3.3% auf 3.6% erh\u00f6ht. In den letzten Jahren ist der IWF mehr mit Senkungen seiner Wachstumsprognosen als mit optimistischen Aussagen aufgefallen&#8230;&#8230;<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #00ccff;\">Sign up for our free newsletter to receive weekly news from BONDWorld <a href=\"http:\/\/www.bond-world.de\/index.php?option=com_acymailing&amp;view=user&amp;Itemid=107\"><span style=\"color: #00ccff;\"><strong>Click here to register for your free copy<\/strong><\/span><\/a><a href=\"http:\/\/www.bond-world.de\/index.php?option=com_acymailing&amp;view=user&amp;Itemid=1023\"><span style=\"color: #00ccff;\"><strong>&nbsp;<\/strong><\/span><\/a><\/span><\/p>\n<hr \/>\n<p style=\"text-align: justify;\"><strong>Dr. Thomas Stucki ist CIO der St.Galler Kantonalbank<\/strong><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">Auch f\u00fcr die n\u00e4chsten Jahre zeigen sich die \u00d6konomen des Fonds optimistisch. Das BIP-Wachstum wird zwar nicht mehr die vor der Finanzkrise \u00fcblichen 5% erreichen, sich aber auf dem aktuell guten Niveau halten. Ein Abdriften in Richtung Rezession sehen sie nicht. Das ist ein positives Signal f\u00fcr die Aktienm\u00e4rkte. Ein stabiles Wachstum der Weltwirtschaft verheisst stabile Gewinnzunahmen f\u00fcr die internationalen Konzerne und damit eine gute fundamentale Basis f\u00fcr die Aktienkurse.<\/p>\n<p style=\"text-align: justify;\">Ich schliesse mich diesem Optimismus an, zumindest f\u00fcr das n\u00e4chste Jahr. Erstmals seit langem tragen sowohl die USA als auch Europa und die Schwellenl\u00e4nder zu einer soliden Weltwirtschaft bei. Der wirtschaftliche Graben zwischen den USA und Europa, der sich vor drei Jahren aufgetan hatte, ist geschlossen. Europa w\u00e4chst heute ebenso stark wie Amerika. Das BIP in der Eurozone hat im dritten Quartal erneut um 0.6% zugenommen.&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Breite abgst\u00fctztes Wachstum<\/strong><\/p>\n<p style=\"text-align: justify;\">Selbst in den Probleml\u00e4ndern wie Italien oder Griechenland zeigen sich Anzeichen f\u00fcr eine Trendwende zum Besseren. In Grossbritannien steigt das BIP mit 0.4% zwar etwas weniger stark. Der bef\u00fcrchtete Einbruch als Folge des Brexits ist bisher aber nicht eingetreten. Die Bank of England sah sich deshalb letzte Woche veranlasst, die im letzten Jahr nach der Brexit-Abstimmung vorsorglich vorgenommene Zinssenkung zu korrigieren und hat die Zinsen um 0.25% angehoben. In China h\u00e4lt sich das BIP-Wachstum knapp unter 7%. Das ist f\u00fcr chinesische Verh\u00e4ltnisse nicht brillant, gen\u00fcgt jedoch, um die Weltwirtschaft anzukurbeln. Als Signal wichtiger als die BIP-Zahlen ist sowieso, dass die Abwertung des Yuan und der Abfluss von Kapital aus China gestoppt wurden.<\/p>\n<p style=\"text-align: justify;\"><strong>Besonderes Augenmerk auf die USA<\/strong><\/p>\n<p style=\"text-align: justify;\">Entscheidend f\u00fcr das weitere Wohl der Weltwirtschaft und damit f\u00fcr die Fortsetzung des Bullenmarktes an den B\u00f6rsen ist und bleibt jedoch die US-Wirtschaft. Diese ist trotz den Hurricanes im dritten Quartal mit 3.0% gewachsen. Der private Konsum als gewichtigste Komponente hielt sich mit einem Plus von 2.4% solide. F\u00fcr die Zukunft positiver ist jedoch der Anstieg der privaten Investitionen um 6.0% zu werten. Die Jobmaschine l\u00e4uft unverdrossen weiter und auch die vorausschauenden Indikatoren wie die ISM-Indizes geben keinen Hinweis, der auf ein Ende des wirtschaftlichen H\u00f6henfluges hindeuten w\u00fcrde. Kommt hinzu, dass mit Jerome Powell die Geldpolitik der graduellen Zinserh\u00f6hungen von Janet Yellen weitergef\u00fchrt wird. Die Gefahr eines durch die Geldpolitik ausgel\u00f6sten Absturzes der Wirtschaft ist somit klein.<\/p>\n<p style=\"text-align: justify;\">Eine mit 3.6% wachsende Weltwirtschaft ist eine gute Basis f\u00fcr die Unternehmen. Die Gewinne der Firmen k\u00f6nnen weiter steigen. Das ist die Grundvoraussetzung daf\u00fcr, dass die nicht mehr billig bewerteten Aktienm\u00e4rkte in den n\u00e4chsten Monaten sich zumindest auf dem heutigen Niveau halten k\u00f6nnen oder gar zu einem Jahresendrallye ansetzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Quelle: BondWorld<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Internationale W\u00e4hrungsfonds IWF hat seine Prognose f\u00fcr das Wachstum der Weltwirtschaft f\u00fcr 2017 von 3.3% auf 3.6% erh\u00f6ht. In den letzten Jahren ist der IWF mehr mit Senkungen seiner Wachstumsprognosen als mit optimistischen Aussagen aufgefallen&#8230;&#8230;<\/p>\n","protected":false},"author":4,"featured_media":4360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"telegram_tosend":false,"telegram_tosend_message":"","telegram_tosend_target":0,"footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[98],"class_list":["post-3137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marktanalyse","tag-st-galler-kantonalbank"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/3137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/comments?post=3137"}],"version-history":[{"count":1,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/3137\/revisions"}],"predecessor-version":[{"id":4962,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/posts\/3137\/revisions\/4962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media\/4360"}],"wp:attachment":[{"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/media?parent=3137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/categories?post=3137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.investmentworld.eu\/ch\/wp-json\/wp\/v2\/tags?post=3137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}